{"id":11422,"date":"2024-02-24T10:40:45","date_gmt":"2024-02-24T08:40:45","guid":{"rendered":"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23.png"},"modified":"2024-02-24T10:40:45","modified_gmt":"2024-02-24T08:40:45","slug":"anfr_2024-02-23","status":"inherit","type":"attachment","link":"https:\/\/wp.rncmobile.net\/index.php\/publications-anfr-et-ou-arcep\/anfr_2024-02-23\/","title":{"rendered":"ANFR_2024-02-23"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-11422","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"144\" src=\"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-300x144.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-300x144.png 300w, https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-1024x492.png 1024w, https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-768x369.png 768w, https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-624x300.png 624w, https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23.png 1359w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1359,"height":653,"file":"2024\/02\/ANFR_2024-02-23.png","filesize":170644,"sizes":{"medium":{"file":"ANFR_2024-02-23-300x144.png","width":300,"height":144,"filesize":38694,"mime_type":"image\/png","source_url":"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-300x144.png"},"large":{"file":"ANFR_2024-02-23-1024x492.png","width":1024,"height":492,"filesize":279298,"mime_type":"image\/png","source_url":"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-1024x492.png"},"thumbnail":{"file":"ANFR_2024-02-23-150x150.png","width":150,"height":150,"filesize":21162,"mime_type":"image\/png","source_url":"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-150x150.png"},"medium_large":{"file":"ANFR_2024-02-23-768x369.png","width":768,"height":369,"filesize":175135,"mime_type":"image\/png","source_url":"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-768x369.png"},"post-thumbnail":{"file":"ANFR_2024-02-23-624x300.png","width":624,"height":300,"filesize":124335,"mime_type":"image\/png","source_url":"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23-624x300.png"},"full":{"file":"ANFR_2024-02-23.png","width":1359,"height":653,"mime_type":"image\/png","source_url":"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5596,"source_url":"https:\/\/wp.rncmobile.net\/wp-content\/uploads\/2024\/02\/ANFR_2024-02-23.png","filename":"ANFR_2024-02-23.png","filesize":170644,"_links":{"self":[{"href":"https:\/\/wp.rncmobile.net\/index.php\/wp-json\/wp\/v2\/media\/11422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.rncmobile.net\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/wp.rncmobile.net\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/wp.rncmobile.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.rncmobile.net\/index.php\/wp-json\/wp\/v2\/comments?post=11422"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":5596,"href":"https:\/\/wp.rncmobile.net\/index.php\/wp-json\/wp\/v2\/pages\/5596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}